{"id":10,"count":2,"description":"","link":"https:\/\/flodesk.com\/blog\/tag\/product-updates\/","name":"product updates","slug":"product-updates","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>product updates Archives - Flodesk<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"product updates Archives - Flodesk\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flodesk.com\/blog\/tag\/product-updates\/\" \/>\n<meta property=\"og:site_name\" content=\"Flodesk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/flodesk.com\/blog\/tag\/product-updates\/\",\"url\":\"https:\/\/flodesk.com\/blog\/tag\/product-updates\/\",\"name\":\"product updates Archives - Flodesk\",\"isPartOf\":{\"@id\":\"https:\/\/flodesk.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/flodesk.com\/blog\/tag\/product-updates\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/flodesk.com\/blog\/tag\/product-updates\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/flodesk.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"product updates\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/flodesk.com\/blog\/#website\",\"url\":\"https:\/\/flodesk.com\/blog\/\",\"name\":\"Flodesk\",\"description\":\"A blog sharing email marketing strategies and best practices for small business owners\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/flodesk.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"product updates Archives - Flodesk","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"product updates Archives - Flodesk","og_url":"https:\/\/flodesk.com\/blog\/tag\/product-updates\/","og_site_name":"Flodesk","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/flodesk.com\/blog\/tag\/product-updates\/","url":"https:\/\/flodesk.com\/blog\/tag\/product-updates\/","name":"product updates Archives - Flodesk","isPartOf":{"@id":"https:\/\/flodesk.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/flodesk.com\/blog\/tag\/product-updates\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/flodesk.com\/blog\/tag\/product-updates\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/flodesk.com\/blog\/"},{"@type":"ListItem","position":2,"name":"product updates"}]},{"@type":"WebSite","@id":"https:\/\/flodesk.com\/blog\/#website","url":"https:\/\/flodesk.com\/blog\/","name":"Flodesk","description":"A blog sharing email marketing strategies and best practices for small business owners","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flodesk.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/flodesk.com\/blog\/wp-json\/wp\/v2\/tags\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flodesk.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/flodesk.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/flodesk.com\/blog\/wp-json\/wp\/v2\/posts?tags=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}